{"id":1838,"date":"2017-06-02T13:54:03","date_gmt":"2017-06-02T11:54:03","guid":{"rendered":"https:\/\/www.maison-piloni.com\/?page_id=1838"},"modified":"2026-07-15T12:12:20","modified_gmt":"2026-07-15T10:12:20","slug":"home","status":"publish","type":"page","link":"https:\/\/www.maison-piloni.com\/fr\/home\/","title":{"rendered":"Bienvenue dans la chambres d&rsquo;h\u00f4tes Maison Piloni"},"content":{"rendered":"<h1>Bienvenue dans la Maison Piloni<\/h1>\n<p>Ce chambres d&rsquo;h\u00f4tes en plein c\u0153ur de la Provence se situe dans la ravissante ville de L\u2019Isle-sur-la Sorgue, \u00e0 25 km \u00e0 l\u2019Est d\u2019Avignon, aux portes du Luberon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue dans la Maison Piloni Ce chambres d&rsquo;h\u00f4tes en plein c\u0153ur de la Provence se situe dans la ravissante ville de L\u2019Isle-sur-la Sorgue, \u00e0 25 km \u00e0 l\u2019Est d\u2019Avignon, aux portes du Luberon.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"open","template":"template-startsite.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1838","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/pages\/1838\/"}],"collection":[{"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/pages\/"}],"about":[{"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/types\/page\/"}],"author":[{"embeddable":true,"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/users\/1\/"}],"replies":[{"embeddable":true,"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/comments\/?post=1838"}],"version-history":[{"count":17,"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/pages\/1838\/revisions\/"}],"predecessor-version":[{"id":4011,"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/pages\/1838\/revisions\/4011\/"}],"wp:attachment":[{"href":"https:\/\/www.maison-piloni.com\/fr\/wp-json\/wp\/v2\/media\/?parent=1838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}